{"id":407,"date":"2022-04-29T23:01:13","date_gmt":"2022-04-29T23:01:13","guid":{"rendered":"https:\/\/www.sorliof.ca\/?page_id=407"},"modified":"2026-07-14T16:51:44","modified_gmt":"2026-07-14T16:51:44","slug":"agricultural-products","status":"publish","type":"page","link":"https:\/\/www.sorliof.ca\/fr\/agricultural-products\/","title":{"rendered":"Produits agricoles"},"content":{"rendered":"<p class=\"wp-block-paragraph\" style=\"text-align: justify;\">Sorliof Canada exporte une s\u00e9lection de produits agricoles canadiens vers les march\u00e9s internationaux. Notre offre comprend des c\u00e9r\u00e9ales, des ol\u00e9agineux, des l\u00e9gumineuses ainsi que d\u2019autres produits agricoles destin\u00e9s aux importateurs, distributeurs, transformateurs et acheteurs institutionnels.<\/p>\r\n<p style=\"text-align: justify;\">Nous adaptons nos offres aux besoins de chaque march\u00e9. Les sp\u00e9cifications des produits, les volumes, les modes de conditionnement et les modalit\u00e9s de livraison sont \u00e9tablis en fonction des exigences des clients et des caract\u00e9ristiques du march\u00e9 de destination.<\/p>\r\n<p style=\"text-align: justify;\">Nos produits proviennent exclusivement de producteurs et de fournisseurs canadiens et sont commercialis\u00e9s en fonction de leur disponibilit\u00e9, des saisons de r\u00e9colte et des exigences applicables au commerce international. Notre portefeuille comprend le bl\u00e9, le bl\u00e9 dur, l\u2019orge, l\u2019avoine, le malt, les graines de canola, l\u2019huile de canola raffin\u00e9e et non raffin\u00e9e, le tourteau de canola, le soja, l\u2019huile de soja raffin\u00e9e et non raffin\u00e9e, le tourteau de soja, les graines de moutarde, les graines de lin, les pois, les pois chiches, les haricots, les lentilles et l\u2019alpiste des Canaries.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center;\"><span style=\"display: inline-block; background: #00aeef; color: white; padding: 12px 26px; border-radius: 6px; font-weight: bold;\">S\u00e9lectionnez un produit ci-dessous pour en savoir plus \u2193<\/span><\/p>\r\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-407 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1502\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/01-wheat.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1502'>\n\t\t\t\tBl\u00e9\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1503\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/02-barley.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1503'>\n\t\t\t\tOrge\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1504\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/03-oats.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1504'>\n\t\t\t\tAvoine\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1505\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/04-malt.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1505'>\n\t\t\t\tMalt\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1507\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/05-soybean.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1507'>\n\t\t\t\tSoja\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1508\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/06-canola.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1508'>\n\t\t\t\tCanola\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1509\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/07-yellow-mustard-seeds.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1509'>\n\t\t\t\tGraines de moutarde\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1510\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/08-flaxseed.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1510'>\n\t\t\t\tGraines de lin\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1511\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/09-peas.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1511'>\n\t\t\t\tPois\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1512\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/10-chickpeas.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1512'>\n\t\t\t\tPoids chiches\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1517\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/15-beans.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1517'>\n\t\t\t\tHaricot\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1516\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/14-lentils.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1516'>\n\t\t\t\tLentilles\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1515\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/13-soybean-meal.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1515'>\n\t\t\t\tTourteau de soja\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1514\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/12-canola-meal.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1514'>\n\t\t\t\tTourteau de canola\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-1513\" srcset=\"https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed-300x300.jpg 300w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed-150x150.jpg 150w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed-768x768.jpg 768w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed-12x12.jpg 12w, https:\/\/www.sorliof.ca\/wp-content\/uploads\/2026\/07\/11-canary-seed.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1513'>\n\t\t\t\tAlpiste des canaries\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\r\n<p style=\"text-align: justify;\">\r\n\r\n<\/p>\r\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n\r\n\r\n\r\n<\/figure>\r\n<p style=\"text-align: justify;\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Sorliof Canada exports a selection of Canadian agricultural products to international markets. Our offering includes grains, oilseeds, pulses and other agricultural products intended for importers, distributors, processors and institutional buyers. We tailor our offerings to the needs of each market. Product specifications, volumes, packaging and delivery terms are established according to customer requirements and the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-407","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/pages\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/comments?post=407"}],"version-history":[{"count":48,"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/pages\/407\/revisions"}],"predecessor-version":[{"id":1542,"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/pages\/407\/revisions\/1542"}],"wp:attachment":[{"href":"https:\/\/www.sorliof.ca\/fr\/wp-json\/wp\/v2\/media?parent=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}